{"id":3,"name":"admin","url":"","description":"","link":"https:\/\/hizbke.org\/en\/author\/admin\/","slug":"admin","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>admin, Author at Hizb ut Tahrir Kenya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hizbke.org\/en\/author\/admin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"admin, Author at Hizb ut Tahrir Kenya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hizbke.org\/en\/author\/admin\/\" \/>\n<meta property=\"og:site_name\" content=\"Hizb ut Tahrir Kenya\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/61df35025704eedf45d9d23c75ffa5b4?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HT_KENYA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/author\\\/admin\\\/\",\"url\":\"https:\\\/\\\/hizbke.org\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin, Author at Hizb ut Tahrir Kenya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/author\\\/admin\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hizbke.org\\\/en\\\/author\\\/admin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/author\\\/admin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hizbke.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for admin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hizbke.org\\\/en\\\/\",\"name\":\"Hizb ut Tahrir Kenya\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hizbke.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#organization\",\"name\":\"Hizb ut Tahrir Kenya\",\"url\":\"https:\\\/\\\/hizbke.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hizbke.org\\\/en\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/hizbke.org\\\/en\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/cropped-3-1.png\",\"width\":306,\"height\":70,\"caption\":\"Hizb ut Tahrir Kenya\"},\"image\":{\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OfisiyahabariHtKenya\\\/\",\"https:\\\/\\\/x.com\\\/HT_KENYA\",\"https:\\\/\\\/www.instagram.com\\\/htkenya\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/#\\\/schema\\\/person\\\/5e8ca7feb88b79abc461e568ffc22120\",\"name\":\"admin\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hizbke.org\\\/en\\\/author\\\/admin\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"admin, Author at Hizb ut Tahrir Kenya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hizbke.org\/en\/author\/admin\/","og_locale":"en_US","og_type":"profile","og_title":"admin, Author at Hizb ut Tahrir Kenya","og_url":"https:\/\/hizbke.org\/en\/author\/admin\/","og_site_name":"Hizb ut Tahrir Kenya","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/61df35025704eedf45d9d23c75ffa5b4?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@HT_KENYA","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/hizbke.org\/en\/author\/admin\/","url":"https:\/\/hizbke.org\/en\/author\/admin\/","name":"admin, Author at Hizb ut Tahrir Kenya","isPartOf":{"@id":"https:\/\/hizbke.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/hizbke.org\/en\/author\/admin\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hizbke.org\/en\/author\/admin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hizbke.org\/en\/author\/admin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hizbke.org\/en\/"},{"@type":"ListItem","position":2,"name":"Archives for admin"}]},{"@type":"WebSite","@id":"https:\/\/hizbke.org\/en\/#website","url":"https:\/\/hizbke.org\/en\/","name":"Hizb ut Tahrir Kenya","description":"","publisher":{"@id":"https:\/\/hizbke.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hizbke.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hizbke.org\/en\/#organization","name":"Hizb ut Tahrir Kenya","url":"https:\/\/hizbke.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hizbke.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hizbke.org\/en\/wp-content\/uploads\/2018\/05\/cropped-3-1.png","contentUrl":"https:\/\/hizbke.org\/en\/wp-content\/uploads\/2018\/05\/cropped-3-1.png","width":306,"height":70,"caption":"Hizb ut Tahrir Kenya"},"image":{"@id":"https:\/\/hizbke.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OfisiyahabariHtKenya\/","https:\/\/x.com\/HT_KENYA","https:\/\/www.instagram.com\/htkenya\/"]},{"@type":"Person","@id":"https:\/\/hizbke.org\/en\/#\/schema\/person\/5e8ca7feb88b79abc461e568ffc22120","name":"admin","mainEntityOfPage":{"@id":"https:\/\/hizbke.org\/en\/author\/admin\/"}}]}},"_links":{"self":[{"href":"https:\/\/hizbke.org\/en\/wp-json\/wp\/v2\/users\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hizbke.org\/en\/wp-json\/wp\/v2\/users"}]}}